{"id":34,"count":1,"description":"","link":"https:\/\/research.bowdoin.edu\/environmental-studies-newsletter\/category\/outdoors\/","name":"Outdoors","slug":"outdoors","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/research.bowdoin.edu\/environmental-studies-newsletter\/wp-json\/wp\/v2\/categories\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/research.bowdoin.edu\/environmental-studies-newsletter\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/research.bowdoin.edu\/environmental-studies-newsletter\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/research.bowdoin.edu\/environmental-studies-newsletter\/wp-json\/wp\/v2\/posts?categories=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}