{"id":57,"count":13,"description":"","link":"https:\/\/research.bowdoin.edu\/robocup\/category\/competition\/robocup-2009\/","name":"RoboCup 2009","slug":"robocup-2009","taxonomy":"category","parent":13,"meta":[],"_links":{"self":[{"href":"https:\/\/research.bowdoin.edu\/robocup\/wp-json\/wp\/v2\/categories\/57","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/research.bowdoin.edu\/robocup\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/research.bowdoin.edu\/robocup\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/research.bowdoin.edu\/robocup\/wp-json\/wp\/v2\/categories\/13"}],"wp:post_type":[{"href":"https:\/\/research.bowdoin.edu\/robocup\/wp-json\/wp\/v2\/posts?categories=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}