{"id":65,"name":"qreeve","url":"","description":"","link":"https:\/\/research.bowdoin.edu\/robocup\/author\/qreeve\/","slug":"qreeve","meta":[],"_links":{"self":[{"href":"https:\/\/research.bowdoin.edu\/robocup\/wp-json\/wp\/v2\/users\/65","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/research.bowdoin.edu\/robocup\/wp-json\/wp\/v2\/users"}]}}